{"id":2315,"date":"2025-10-06T14:42:18","date_gmt":"2025-10-06T18:42:18","guid":{"rendered":"https:\/\/gmsh.ca\/articles\/ghb\/"},"modified":"2026-02-02T16:38:49","modified_gmt":"2026-02-02T21:38:49","slug":"ghb","status":"publish","type":"gmsh_article","link":"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/","title":{"rendered":"GHB"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">(G, Gina, \u00e1gua)<\/h2>\n\n<h2 class=\"wp-block-heading\">O que \u00e9<\/h2>\n\n<p class=\"wp-block-paragraph\">O GHB \u00e9 um forte depressor, geralmente encontrado como um l\u00edquido claro e oleoso. Ele pode ter sabor salgado, doce ou n\u00e3o ter sabor algum. \u00c0s vezes, parece turvo. <strong>Em<\/strong>ambientes de PnP, o GHB \u00e9 frequentemente usado para reduzir a dor, relaxar os m\u00fasculos (inclusive o esf\u00edncter anal) e aumentar o prazer sexual.  <\/p>\n\n<h2 class=\"wp-block-heading\">Como funciona<\/h2>\n\n<p class=\"wp-block-paragraph\">O GHB afeta duas partes do c\u00e9rebro: Os receptores GABA e seus pr\u00f3prios receptores especiais de GHB. Juntos, eles desaceleram o sistema nervoso central e podem fazer com que voc\u00ea se sinta calmo, sonolento ou menos coordenado. Voc\u00ea tamb\u00e9m pode sentir uma pequena explos\u00e3o de energia  <\/p>\n\n<p class=\"wp-block-paragraph\">A intensidade dos efeitos do GHB depende de fatores f\u00edsicos, como a quantidade de comida que voc\u00ea ingeriu antes (mais lenta para sentir os efeitos) e o quanto voc\u00ea est\u00e1 descansado (mais propenso a &#8220;g-out&#8221; quando est\u00e1 cansado demais). Fique atento a como voc\u00ea se sente antes de decidir tomar uma dose. <\/p>\n\n<h2 class=\"wp-block-heading\">Como voc\u00ea pode se sentir<\/h2>\n\n<h3 class=\"wp-block-heading\">Doses baixas a moderadas:<\/h3>\n\n<ul class=\"wp-block-list\">\n<li class=\"wp-block-list-item\">Calmo e zumbido, como depois de um ou dois drinques<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Excitado, sens\u00edvel ao toque.<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Quente e suave<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\">Doses mais altas:<\/h3>\n\n<ul class=\"wp-block-list\">\n<li class=\"wp-block-list-item\">Tontura ou confus\u00e3o<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Aceno de cabe\u00e7a e fala arrastada ou interrompida<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Irritabilidade ou agressividade<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Perda de consci\u00eancia, convuls\u00f5es ou dificuldade para respirar<\/li>\n\n\n\n<li class=\"wp-block-list-item\">V\u00f4mito ou desmaio<\/li>\n\n\n\n<li class=\"wp-block-list-item\">O risco de overdose aumenta rapidamente com doses maiores<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">GBL + BDO  <\/h2>\n\n<p class=\"wp-block-paragraph\">A GBL e o BDO s\u00e3o an\u00e1logos do GHB, o que significa que s\u00e3o muito semelhantes ao GHB em n\u00edvel molecular, mas diferem um pouco. Ambos t\u00eam efeitos semelhantes aos do GHB, mas s\u00e3o muito mais r\u00e1pidos e <a href=\"http:\/\/stronger.it\">fortes<\/a>, o que significa que voc\u00ea deve tomar uma dose menor. Embora a \u00fanica maneira 100% certa de identificar o que voc\u00ea tem de GHB seja fazer o teste<strong>. <\/strong>No entanto, h\u00e1 algumas maneiras de ajud\u00e1-lo a fazer uma estimativa informada sobre o que voc\u00ea est\u00e1 tomando, o que pode ser visto na tabela em Uso e dosagem. <\/p>\n\n<h2 class=\"wp-block-heading\">Uso e dosagem<\/h2>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"655\" height=\"502\" src=\"https:\/\/gmsh.ca\/wp-content\/uploads\/2025\/10\/image-3.png\" alt=\"\" class=\"wp-image-518\" srcset=\"https:\/\/gmsh.ca\/wp-content\/uploads\/2025\/10\/image-3.png 655w, https:\/\/gmsh.ca\/wp-content\/uploads\/2025\/10\/image-3-300x230.png 300w\" sizes=\"auto, (max-width: 655px) 100vw, 655px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Mistura com outras drogas<\/h2>\n\n<p class=\"wp-block-paragraph\">A mistura com outros depressores \u00e9 especialmente perigosa. Evite consumir: <\/p>\n\n<ul class=\"wp-block-list\">\n<li class=\"wp-block-list-item\">\u00c1lcool<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Benzodiazep\u00ednicos<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Cetamina<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Opioides<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Sempre pergunte a um profissional de sa\u00fade sobre os medicamentos prescritos.<\/p>\n\n<h2 class=\"wp-block-heading\">Seguran\u00e7a e uso mais seguro<\/h2>\n\n<ul class=\"wp-block-list\">\n<li class=\"wp-block-list-item\">Use uma seringa ou balan\u00e7a para medir sua dose com precis\u00e3o (uma tampa de frasco n\u00e3o \u00e9 uma unidade de medida padr\u00e3o)<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Evite misturar com \u00e1lcool ou outros depressores<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Espere antes de refazer a dose &#8211; n\u00e3o adivinhe, use um rastreador ou cron\u00f4metro em seu telefone para espa\u00e7ar as doses.<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Use com amigos de confian\u00e7a que possam ajudar, se necess\u00e1rio<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Mantenha as informa\u00e7\u00f5es de contato de emerg\u00eancia \u00e0 m\u00e3o<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Conhe\u00e7a os sinais de overdose e aja rapidamente se eles aparecerem<\/li>\n\n\n\n<li class=\"wp-block-list-item\">Tente evitar o uso isolado de GHB\/GBL\/BDO.<\/li>\n<\/ul>\n\n<h2 class=\"wp-block-heading\">Resposta a emerg\u00eancias G &#8211; Recursos<\/h2>\n\n<p class=\"wp-block-paragraph\">O mercado de GHB em Ont\u00e1rio est\u00e1 mudando e o gbMSM que Party n&#8217; Play est\u00e1 soando o alarme. O G-emergency Response \u00e9 um grupo de base de homens queer que t\u00eam experi\u00eancia com PnP e GHB e querem manter sua comunidade segura \u00e0 luz de v\u00e1rias mortes relacionadas ao GHB no outono de 2023. <\/p>\n\n<p class=\"wp-block-paragraph\">Em parceria com o GMSH e o CBRC, eles desenvolveram um conjunto de cart\u00f5es postais com informa\u00e7\u00f5es essenciais sobre a seguran\u00e7a do GHB, abrangendo os seguintes t\u00f3picos:<\/p>\n\n<ol class=\"wp-block-list\">\n<li class=\"wp-block-list-item\"><strong>&#8220;O que h\u00e1 em meu frasco?&#8221; <\/strong>&#8211; Distingue GHB, GBL e BDO, aconselhando ajustes de dose por subst\u00e2ncia, juntamente com informa\u00e7\u00f5es sobre o in\u00edcio dos efeitos e a dura\u00e7\u00e3o.<\/li>\n\n\n\n<li class=\"wp-block-list-item\"><strong>&#8220;Dose Tracker <\/strong>&#8221; &#8211; Facilita o monitoramento da dose, reduzindo as overdoses acidentais.<\/li>\n\n\n\n<li class=\"wp-block-list-item\"><strong>Antes de tomar a dose<\/strong> &#8211; O que afeta a alta e uma lista de verifica\u00e7\u00e3o que voc\u00ea deve seguir antes de medir a dose.<\/li>\n\n\n\n<li class=\"wp-block-list-item\"><strong>&#8220;How to respond to an G-mergency<\/strong> &#8221; (<strong>Como responder a uma emerg\u00eancia G)<\/strong> &#8211; Oferece insights sobre o gerenciamento de situa\u00e7\u00f5es de envenenamento\/overdose e no\u00e7\u00f5es b\u00e1sicas sobre a Lei do Bom Samaritano.<\/li>\n<\/ol>\n\n<p class=\"wp-block-paragraph\">Esses recursos t\u00eam como objetivo salvar vidas e foram criados por e para usu\u00e1rios de GHB\/GBL e BDO. Eles s\u00e3o acess\u00edveis, f\u00e1ceis de usar e compartilh\u00e1veis, promovendo decis\u00f5es informadas. <\/p>\n\n<p class=\"wp-block-paragraph\">Esses cart\u00f5es postais se baseiam em informa\u00e7\u00f5es do DanceSafe, do Alliance for Collaborative Drug Checking Group, do The Loop e de experi\u00eancias pessoais. Eles foram revisados pelo Servi\u00e7o de Verifica\u00e7\u00e3o de Drogas de Toronto, com insights do European Chemsex Forum, do GMSH e do CBRC. <\/p>\n\n<h2 class=\"wp-block-heading\">A droga e a lei<\/h2>\n\n<p class=\"wp-block-paragraph\">A posse ou venda de GHB \u00e9 ilegal no Canad\u00e1. Mas, de acordo com a Lei de Overdose de Drogas do Bom Samaritano, qualquer pessoa pode ligar para o 911 em caso de overdose sem medo de ser acusada de simples posse. Isso se aplica mesmo se voc\u00ea estiver em liberdade condicional ou liberdade provis\u00f3ria.  <\/p>\n\n<h2 class=\"wp-block-heading\">Considera\u00e7\u00f5es finais<\/h2>\n\n<p class=\"wp-block-paragraph\">O GHB pode ser relaxante e \u00edntimo, mas a linha entre o prazer e o dano \u00e9 t\u00eanue, especialmente quando a dosagem n\u00e3o \u00e9 exata ou quando outros depressores s\u00e3o adicionados. Nos espa\u00e7os de PnP, o consentimento informado e o uso mais seguro mant\u00eam a experi\u00eancia positiva e respeitosa. <\/p>\n\n<p class=\"wp-block-paragraph\">Cuidem de voc\u00eas e uns dos outros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(G, Gina, \u00e1gua) O que \u00e9 O GHB \u00e9 um forte depressor, geralmente encontrado como um l\u00edquido claro e oleoso. Ele pode ter sabor salgado, doce ou n\u00e3o ter sabor algum. \u00c0s vezes, parece turvo. Emambientes de PnP, o GHB \u00e9 frequentemente usado para reduzir a dor, relaxar os m\u00fasculos (inclusive o esf\u00edncter anal) e<a href=\"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/\">Continuar lendo <span class=\"sr-only\">&#8220;GHB&#8221;<\/span><\/a><\/p>\n","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false},"gmsh_section":[177],"class_list":["post-2315","gmsh_article","type-gmsh_article","status-publish","hentry","gmsh_section-informacoes-sobre-medicamentos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GHB - GMSH.ca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GHB - GMSH.ca\" \/>\n<meta property=\"og:description\" content=\"(G, Gina, \u00e1gua) O que \u00e9 O GHB \u00e9 um forte depressor, geralmente encontrado como um l\u00edquido claro e oleoso. Ele pode ter sabor salgado, doce ou n\u00e3o ter sabor algum. \u00c0s vezes, parece turvo. Emambientes de PnP, o GHB \u00e9 frequentemente usado para reduzir a dor, relaxar os m\u00fasculos (inclusive o esf\u00edncter anal) eContinuar lendo &quot;GHB&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/\" \/>\n<meta property=\"og:site_name\" content=\"GMSH.ca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GMSHAlliance\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T21:38:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gmsh.ca\/wp-content\/uploads\/2025\/10\/image-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"655\" \/>\n\t<meta property=\"og:image:height\" content=\"502\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gmshalliance\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/articles\\\/ghb\\\/\",\"url\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/articles\\\/ghb\\\/\",\"name\":\"GHB - GMSH.ca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/articles\\\/ghb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/articles\\\/ghb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gmsh.ca\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/image-3.png\",\"datePublished\":\"2025-10-06T18:42:18+00:00\",\"dateModified\":\"2026-02-02T21:38:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/articles\\\/ghb\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/articles\\\/ghb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/articles\\\/ghb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gmsh.ca\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/image-3.png\",\"contentUrl\":\"https:\\\/\\\/gmsh.ca\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/image-3.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/articles\\\/ghb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Articles\",\"item\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/articles\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GHB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/\",\"name\":\"Gay Men\u2019s Sexual Health Alliance (GMSH)\",\"description\":\"Empowering Connection and Well-being for 2SGBTQ+ Men\",\"publisher\":{\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/#organization\"},\"alternateName\":\"GMSH.ca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/#organization\",\"name\":\"Gay Men\u2019s Sexual Health Alliance (GMSH)\",\"url\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gmsh.ca\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/gmsh-favicon.png\",\"contentUrl\":\"https:\\\/\\\/gmsh.ca\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/gmsh-favicon.png\",\"width\":340,\"height\":340,\"caption\":\"Gay Men\u2019s Sexual Health Alliance (GMSH)\"},\"image\":{\"@id\":\"https:\\\/\\\/gmsh.ca\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GMSHAlliance\",\"https:\\\/\\\/x.com\\\/gmshalliance\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gay-men-s-sexual-health-alliance\\\/?originalSubdomain=ca\",\"https:\\\/\\\/www.instagram.com\\\/gaymenssexualhealthalliance\\\/\",\"https:\\\/\\\/www.youtube.com\\\/gaymenssexualhealthalliance\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GHB - GMSH.ca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/","og_locale":"pt_BR","og_type":"article","og_title":"GHB - GMSH.ca","og_description":"(G, Gina, \u00e1gua) O que \u00e9 O GHB \u00e9 um forte depressor, geralmente encontrado como um l\u00edquido claro e oleoso. Ele pode ter sabor salgado, doce ou n\u00e3o ter sabor algum. \u00c0s vezes, parece turvo. Emambientes de PnP, o GHB \u00e9 frequentemente usado para reduzir a dor, relaxar os m\u00fasculos (inclusive o esf\u00edncter anal) eContinuar lendo \"GHB\"","og_url":"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/","og_site_name":"GMSH.ca","article_publisher":"https:\/\/www.facebook.com\/GMSHAlliance","article_modified_time":"2026-02-02T21:38:49+00:00","og_image":[{"width":655,"height":502,"url":"https:\/\/gmsh.ca\/wp-content\/uploads\/2025\/10\/image-3.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@gmshalliance","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/","url":"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/","name":"GHB - GMSH.ca","isPartOf":{"@id":"https:\/\/gmsh.ca\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/#primaryimage"},"image":{"@id":"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/#primaryimage"},"thumbnailUrl":"https:\/\/gmsh.ca\/wp-content\/uploads\/2025\/10\/image-3.png","datePublished":"2025-10-06T18:42:18+00:00","dateModified":"2026-02-02T21:38:49+00:00","breadcrumb":{"@id":"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/#primaryimage","url":"https:\/\/gmsh.ca\/wp-content\/uploads\/2025\/10\/image-3.png","contentUrl":"https:\/\/gmsh.ca\/wp-content\/uploads\/2025\/10\/image-3.png"},{"@type":"BreadcrumbList","@id":"https:\/\/gmsh.ca\/pt-br\/articles\/ghb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/gmsh.ca\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Articles","item":"https:\/\/gmsh.ca\/pt-br\/articles\/"},{"@type":"ListItem","position":3,"name":"GHB"}]},{"@type":"WebSite","@id":"https:\/\/gmsh.ca\/pt-br\/#website","url":"https:\/\/gmsh.ca\/pt-br\/","name":"Gay Men\u2019s Sexual Health Alliance (GMSH)","description":"Empowering Connection and Well-being for 2SGBTQ+ Men","publisher":{"@id":"https:\/\/gmsh.ca\/pt-br\/#organization"},"alternateName":"GMSH.ca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gmsh.ca\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/gmsh.ca\/pt-br\/#organization","name":"Gay Men\u2019s Sexual Health Alliance (GMSH)","url":"https:\/\/gmsh.ca\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/gmsh.ca\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/gmsh.ca\/wp-content\/uploads\/2026\/01\/gmsh-favicon.png","contentUrl":"https:\/\/gmsh.ca\/wp-content\/uploads\/2026\/01\/gmsh-favicon.png","width":340,"height":340,"caption":"Gay Men\u2019s Sexual Health Alliance (GMSH)"},"image":{"@id":"https:\/\/gmsh.ca\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GMSHAlliance","https:\/\/x.com\/gmshalliance","https:\/\/www.linkedin.com\/company\/gay-men-s-sexual-health-alliance\/?originalSubdomain=ca","https:\/\/www.instagram.com\/gaymenssexualhealthalliance\/","https:\/\/www.youtube.com\/gaymenssexualhealthalliance"]}]}},"_links":{"self":[{"href":"https:\/\/gmsh.ca\/pt-br\/wp-json\/wp\/v2\/gmsh_article\/2315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gmsh.ca\/pt-br\/wp-json\/wp\/v2\/gmsh_article"}],"about":[{"href":"https:\/\/gmsh.ca\/pt-br\/wp-json\/wp\/v2\/types\/gmsh_article"}],"wp:attachment":[{"href":"https:\/\/gmsh.ca\/pt-br\/wp-json\/wp\/v2\/media?parent=2315"}],"wp:term":[{"taxonomy":"gmsh_section","embeddable":true,"href":"https:\/\/gmsh.ca\/pt-br\/wp-json\/wp\/v2\/gmsh_section?post=2315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}